{"id":2731,"count":1,"description":"","link":"https:\/\/www.kabotron.com.br\/blog\/tag\/fio-eletrico-para-luminaria\/","name":"fio el\u00e9trico para lumin\u00e1ria","slug":"fio-eletrico-para-luminaria","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivo de fio el\u00e9trico para lumin\u00e1ria - Kabotron<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kabotron.com.br\/blog\/tag\/fio-eletrico-para-luminaria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de fio el\u00e9trico para lumin\u00e1ria - Kabotron\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kabotron.com.br\/blog\/tag\/fio-eletrico-para-luminaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Kabotron\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.kabotron.com.br\/blog\/tag\/fio-eletrico-para-luminaria\/\",\"url\":\"https:\/\/www.kabotron.com.br\/blog\/tag\/fio-eletrico-para-luminaria\/\",\"name\":\"Arquivo de fio el\u00e9trico para lumin\u00e1ria - Kabotron\",\"isPartOf\":{\"@id\":\"https:\/\/www.kabotron.com.br\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.kabotron.com.br\/blog\/tag\/fio-eletrico-para-luminaria\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kabotron.com.br\/blog\/tag\/fio-eletrico-para-luminaria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.kabotron.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"fio el\u00e9trico para lumin\u00e1ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kabotron.com.br\/blog\/#website\",\"url\":\"https:\/\/www.kabotron.com.br\/blog\/\",\"name\":\"Kabotron\",\"description\":\"Blog - Kabotron\",\"publisher\":{\"@id\":\"https:\/\/www.kabotron.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kabotron.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.kabotron.com.br\/blog\/#organization\",\"name\":\"Kabotron\",\"url\":\"https:\/\/www.kabotron.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.kabotron.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.kabotron.com.br\/blog\/wp-content\/uploads\/2024\/01\/logo-4.png\",\"contentUrl\":\"https:\/\/www.kabotron.com.br\/blog\/wp-content\/uploads\/2024\/01\/logo-4.png\",\"width\":350,\"height\":150,\"caption\":\"Kabotron\"},\"image\":{\"@id\":\"https:\/\/www.kabotron.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de fio el\u00e9trico para lumin\u00e1ria - Kabotron","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kabotron.com.br\/blog\/tag\/fio-eletrico-para-luminaria\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de fio el\u00e9trico para lumin\u00e1ria - Kabotron","og_url":"https:\/\/www.kabotron.com.br\/blog\/tag\/fio-eletrico-para-luminaria\/","og_site_name":"Kabotron","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.kabotron.com.br\/blog\/tag\/fio-eletrico-para-luminaria\/","url":"https:\/\/www.kabotron.com.br\/blog\/tag\/fio-eletrico-para-luminaria\/","name":"Arquivo de fio el\u00e9trico para lumin\u00e1ria - Kabotron","isPartOf":{"@id":"https:\/\/www.kabotron.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.kabotron.com.br\/blog\/tag\/fio-eletrico-para-luminaria\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kabotron.com.br\/blog\/tag\/fio-eletrico-para-luminaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.kabotron.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"fio el\u00e9trico para lumin\u00e1ria"}]},{"@type":"WebSite","@id":"https:\/\/www.kabotron.com.br\/blog\/#website","url":"https:\/\/www.kabotron.com.br\/blog\/","name":"Kabotron","description":"Blog - Kabotron","publisher":{"@id":"https:\/\/www.kabotron.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kabotron.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.kabotron.com.br\/blog\/#organization","name":"Kabotron","url":"https:\/\/www.kabotron.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.kabotron.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.kabotron.com.br\/blog\/wp-content\/uploads\/2024\/01\/logo-4.png","contentUrl":"https:\/\/www.kabotron.com.br\/blog\/wp-content\/uploads\/2024\/01\/logo-4.png","width":350,"height":150,"caption":"Kabotron"},"image":{"@id":"https:\/\/www.kabotron.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kabotron.com.br\/blog\/wp-json\/wp\/v2\/tags\/2731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kabotron.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.kabotron.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.kabotron.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=2731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}